{"id":318,"count":2,"description":"","link":"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/","name":"colegio liceo europeo","slug":"colegio-liceo-europeo-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>colegio liceo europeo archivos - Colegio biling\u00fce privado en Madrid | Liceo Europeo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"colegio liceo europeo archivos - Colegio biling\u00fce privado en Madrid | Liceo Europeo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio biling\u00fce privado en Madrid | Liceo Europeo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LiceoEuropeo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/tag\\\/colegio-liceo-europeo-en\\\/\",\"url\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/tag\\\/colegio-liceo-europeo-en\\\/\",\"name\":\"colegio liceo europeo archivos - Colegio biling\u00fce privado en Madrid | Liceo Europeo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/tag\\\/colegio-liceo-europeo-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/tag\\\/colegio-liceo-europeo-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"colegio liceo europeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/\",\"name\":\"Colegio biling\u00fce privado en Madrid | Liceo Europeo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/#organization\",\"name\":\"Colegio biling\u00fce privado en Madrid | Liceo Europeo\",\"url\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/liceo-europeo.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Logo_liceo_europeo.png\",\"contentUrl\":\"https:\\\/\\\/liceo-europeo.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Logo_liceo_europeo.png\",\"width\":805,\"height\":118,\"caption\":\"Colegio biling\u00fce privado en Madrid | Liceo Europeo\"},\"image\":{\"@id\":\"https:\\\/\\\/liceo-europeo.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/liceoeuropeo\",\"https:\\\/\\\/x.com\\\/LiceoEuropeo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"colegio liceo europeo archivos - Colegio biling\u00fce privado en Madrid | Liceo Europeo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/","og_locale":"en_US","og_type":"article","og_title":"colegio liceo europeo archivos - Colegio biling\u00fce privado en Madrid | Liceo Europeo","og_url":"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/","og_site_name":"Colegio biling\u00fce privado en Madrid | Liceo Europeo","twitter_card":"summary_large_image","twitter_site":"@LiceoEuropeo","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/","url":"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/","name":"colegio liceo europeo archivos - Colegio biling\u00fce privado en Madrid | Liceo Europeo","isPartOf":{"@id":"https:\/\/liceo-europeo.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/liceo-europeo.es\/en\/tag\/colegio-liceo-europeo-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/liceo-europeo.es\/en\/"},{"@type":"ListItem","position":2,"name":"colegio liceo europeo"}]},{"@type":"WebSite","@id":"https:\/\/liceo-europeo.es\/en\/#website","url":"https:\/\/liceo-europeo.es\/en\/","name":"Colegio biling\u00fce privado en Madrid | Liceo Europeo","description":"","publisher":{"@id":"https:\/\/liceo-europeo.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/liceo-europeo.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/liceo-europeo.es\/en\/#organization","name":"Colegio biling\u00fce privado en Madrid | Liceo Europeo","url":"https:\/\/liceo-europeo.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/liceo-europeo.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/liceo-europeo.es\/wp-content\/uploads\/2025\/02\/Logo_liceo_europeo.png","contentUrl":"https:\/\/liceo-europeo.es\/wp-content\/uploads\/2025\/02\/Logo_liceo_europeo.png","width":805,"height":118,"caption":"Colegio biling\u00fce privado en Madrid | Liceo Europeo"},"image":{"@id":"https:\/\/liceo-europeo.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/liceoeuropeo","https:\/\/x.com\/LiceoEuropeo"]}]}},"_links":{"self":[{"href":"https:\/\/liceo-europeo.es\/en\/wp-json\/wp\/v2\/tags\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liceo-europeo.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/liceo-europeo.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/liceo-europeo.es\/en\/wp-json\/wp\/v2\/posts?tags=318"},{"href":"https:\/\/liceo-europeo.es\/en\/wp-json\/wp\/v2\/pages?tags=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}